{"id":5565,"count":1,"description":"","link":"https:\/\/digilent.com\/blog\/tag\/private-lte-network\/","name":"private LTE network","slug":"private-lte-network","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/tags\/5565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/posts?tags=5565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}