{"id":5558,"count":1,"description":"","link":"https:\/\/digilent.com\/blog\/tag\/ais-monitoring\/","name":"AIS monitoring","slug":"ais-monitoring","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/tags\/5558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/posts?tags=5558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}