{"id":5529,"count":2,"description":"","link":"https:\/\/digilent.com\/blog\/tag\/eclypse-z7\/","name":"Eclypse Z7","slug":"eclypse-z7","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/tags\/5529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/digilent.com\/blog\/wp-json\/wp\/v2\/posts?tags=5529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}